{"id":666,"date":"2018-02-27T09:23:40","date_gmt":"2018-02-27T08:23:40","guid":{"rendered":"http:\/\/www.gisaski.eus\/site\/?p=666"},"modified":"2018-03-20T18:02:41","modified_gmt":"2018-03-20T17:02:41","slug":"alde-zaharra-se-lleva-partido-la-jornada","status":"publish","type":"post","link":"https:\/\/www.gisaski.eus\/es\/alde-zaharra-se-lleva-partido-la-jornada\/","title":{"rendered":"Alde Zaharra se lleva el partido de la jornada"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Este fin de semana ten\u00edamos un duelo de mucho nivel entre dos equipos que est\u00e1n en muy buena forma. Alde Zaharra y Zast se med\u00edan en Donosti en un encuentro muy importante de cara a la parte alta de la clasificaci\u00f3n. Los donostiarras se hicieron fuertes en casa y supieron llevarse el partido ante los de Zarautz (56-53) para igualarles a 12 victorias en la clasificaci\u00f3n. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los dos primeros clasificados no fallaron esta jornada. Akideba Ointxe se impuso con autoridad a Irauli Bosteko (89-68) para seguir como l\u00edder en solitario. Detr\u00e1s suyo siguen los chicos de Donosti Dolphins que vencieron por un c\u00f3modo 74-45 a Alo\u00f1a Mendi. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el resto de la jornada, Mundarro La Salle se llev\u00f3 el triunfo ante el Atl\u00e9tico San Sebastian y deja a los de Astigarraga en la zona tranquila. Askatuak venci\u00f3 a DKS para hacerse con el derby donostiarra y TAKE se impuso con comodidad a Viento Sur. Por \u00faltimo. Errotaundi ISB gan\u00f3 en Ir\u00fan lo que permite a los de Azpeitia seguir luchando por estar en la pelea.<\/span><\/p>\n<p style=\"text-align: right;\"><b>FGB<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este fin de semana ten\u00edamos un duelo de mucho nivel entre dos equipos que est\u00e1n en muy buena forma. Alde Zaharra y Zast se&#8230;<\/p>\n","protected":false},"author":2,"featured_media":212,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[73],"tags":[65,37,53,98,54],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/666"}],"collection":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/comments?post=666"}],"version-history":[{"count":0,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media\/212"}],"wp:attachment":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media?parent=666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/categories?post=666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/tags?post=666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}