{"id":5947,"date":"2024-09-10T11:45:58","date_gmt":"2024-09-10T09:45:58","guid":{"rendered":"https:\/\/www.gisaski.eus\/?p=5947\/"},"modified":"2024-09-10T11:47:49","modified_gmt":"2024-09-10T09:47:49","slug":"final3x3gisaskizirkuitua","status":"publish","type":"post","link":"https:\/\/www.gisaski.eus\/es\/final3x3gisaskizirkuitua\/","title":{"rendered":"FINAL 3X3 GISASKI ZIRKUITUA"},"content":{"rendered":"<p><strong>Final del 3&#215;3 Gisaski Zirkuitua en Txomin: BIGI se corona campe\u00f3n<\/strong><\/p>\n<p>El pasado s\u00e1bado, 7 de septiembre, se vivi\u00f3 una jornada de baloncesto vibrante en el barrio de Txomin, Donostia, con la celebraci\u00f3n de la final del 3&#215;3 Gisaski Zirkuitua. Tras varios meses de intensa competici\u00f3n, los seis mejores equipos del campeonato se dieron cita para luchar por el ansiado trofeo.<\/p>\n<p>El torneo comenz\u00f3 a las 12:00 del mediod\u00eda, reuniendo a jugadores y aficionados en un ambiente cargado de emoci\u00f3n y deportividad. A lo largo de la ma\u00f1ana, los equipos mostraron todo su esfuerzo, destreza y trabajo en equipo, con partidos muy disputados que mantuvieron la atenci\u00f3n del p\u00fablico.<\/p>\n<p>El cl\u00edmax lleg\u00f3 alrededor de las 14:30, cuando BIGI se alz\u00f3 con el t\u00edtulo de campe\u00f3n al derrotar al equipo KEBAB TEAM con un contundente resultado de 21-12 en la gran final. La actuaci\u00f3n de BIGI fue dominante desde el inicio, mostrando una clara superioridad tanto en ataque como en defensa, lo que les permiti\u00f3 asegurarse la victoria y llevarse el trofeo a casa.<\/p>\n<p>Desde la organizaci\u00f3n del torneo, agradecemos a todos los equipos que participaron a lo largo de estos meses de competici\u00f3n, demostrando su compromiso y pasi\u00f3n por el baloncesto. Igualmente, gracias tambi\u00e9n a todos aquellos que os hab\u00e9is acercado a animar y disfrutar de los emocionantes encuentros.<\/p>\n<p>La final del 3&#215;3 Gisaski Zirkuitua no solo destac\u00f3 por la alta calidad del juego, sino tambi\u00e9n por el ambiente familiar y la camarader\u00eda que se vivi\u00f3 en Txomin, haciendo de esta jornada un gran cierre para una temporada memorable.<\/p>\n<p><strong>\u00a1Felicidades a BIGI por su victoria y gracias a todos por hacer de este torneo un \u00e9xito!<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-5949\" src=\"https:\/\/www.gisaski.eus\/site\/contenido\/media\/diseno-sin-titulo-12.png\" alt=\"\" width=\"6912\" height=\"3456\" srcset=\"https:\/\/www.gisaski.eus\/site\/contenido\/media\/diseno-sin-titulo-12.png 6912w, https:\/\/www.gisaski.eus\/site\/contenido\/media\/diseno-sin-titulo-12-768x384.png 768w, https:\/\/www.gisaski.eus\/site\/contenido\/media\/diseno-sin-titulo-12-1536x768.png 1536w, https:\/\/www.gisaski.eus\/site\/contenido\/media\/diseno-sin-titulo-12-2048x1024.png 2048w\" sizes=\"(max-width: 6912px) 100vw, 6912px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Final del 3&#215;3 Gisaski Zirkuitua en Txomin: BIGI se corona campe\u00f3n El pasado s\u00e1bado, 7 de septiembre, se vivi\u00f3 una jornada de baloncesto vibrante&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5948,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[238,73,6],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/5947"}],"collection":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/comments?post=5947"}],"version-history":[{"count":0,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/5947\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media\/5948"}],"wp:attachment":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media?parent=5947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/categories?post=5947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/tags?post=5947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}