{"id":5661,"date":"2023-12-01T14:28:35","date_gmt":"2023-12-01T13:28:35","guid":{"rendered":"https:\/\/www.gisaski.eus\/?p=5661\/"},"modified":"2023-12-01T14:28:35","modified_gmt":"2023-12-01T13:28:35","slug":"pj-23-12-03","status":"publish","type":"post","link":"https:\/\/www.gisaski.eus\/es\/pj-23-12-03\/","title":{"rendered":"PREVIA DE LA JORNADA"},"content":{"rendered":"<p>Se presenta una jornada muy emocionante este fin de semana.<\/p>\n<p>Ya en Senior Masculino nos podemos encontrar varios partidos importantes, entre los que destacamos uno de cada grupo; arri BKL contra Ama Guadalupekoa Ikasbasket en el grupo 1 y Astigarragako Mundarro contra Loyola Hoops 21 en el grupo 2, ambos de 1\u00aa Divisi\u00f3n y luchando por el cuarto puesto para dar un paso hacia la entrada en el grupo de ascenso. En el grupo 1 de 3\u00aa Divisi\u00f3n tambi\u00e9n tenemos un enfrentamiento directo de este tipo entre Ostadar SKT y Oiarso OSKT. En Femenino destaca el partido de 2\u00aa Divisi\u00f3n entre Ganboa Hoops y Eskoriatza KE, que determinar\u00e1 si se iguala la parte alta de la clasificaci\u00f3n o se abre m\u00e1s brecha entre los equipos en cabeza y los siguientes.<\/p>\n<p>En Junior nos encontramos en la Oro Masculina con un arri BKL Oria &#8211; Pressing Askatuak, primero contra tercero, muy importante de cara al ascenso directo a Liga Vasca. Veremos en el resto de grupos como se desarrollan los resultados para determinar las clasificaciones de cara a la siguiente fase.<\/p>\n<p>Tambi\u00e9n en Cadete Oro Masculino nos podemos encontrar con un partido muy importante, que podr\u00eda ser decisivo, para el ascenso directo a Liga Vasca; Easo Basket Comercial Azkue contra Zast &amp; Furious. Si ganan los locales certificar\u00e1n el ascenso matem\u00e1tico. Ning\u00fan duelo destacado en el resto de grupos.<\/p>\n<p>Se reanudar\u00e1 el partido suspendido de Rendimiento Plata Femenino entre Andraitz KE y Montajes Olaizola ISB, partido destacado entre todos los grupos de Infantil, pues ocupan el primer y segundo lugar de su clasificaci\u00f3n estando empatados a victorias.<\/p>\n<p>\u00a1A disfrutar de una jornada de mucha emoci\u00f3n!\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se presenta una jornada muy emocionante este fin de semana. Ya en Senior Masculino nos podemos encontrar varios partidos importantes, entre los que destacamos&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5660,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[73,6],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/5661"}],"collection":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/comments?post=5661"}],"version-history":[{"count":0,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/5661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media\/5660"}],"wp:attachment":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media?parent=5661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/categories?post=5661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/tags?post=5661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}