{"id":5320,"date":"2023-02-21T17:21:40","date_gmt":"2023-02-21T16:21:40","guid":{"rendered":"https:\/\/www.gisaski.eus\/?p=5320\/"},"modified":"2023-02-21T17:21:40","modified_gmt":"2023-02-21T16:21:40","slug":"tecnificacion-gsf-2023","status":"publish","type":"post","link":"https:\/\/www.gisaski.eus\/es\/tecnificacion-gsf-2023\/","title":{"rendered":"Tecnificaci\u00f3n GSF 2023."},"content":{"rendered":"<p style=\"font-weight: 400;\"><span style=\"color: #000000;\">Como todas las temporadas vamos adelantando la informaci\u00f3n correspondiente a las tecnificaciones organizadas por esta Federaci\u00f3n y que dar\u00e1n el pistoletazo de salida en breve.\u00a0<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"color: #000000;\">Como ya hicimos la pasada temporada, las tecnificaciones ser\u00e1n comarcales e ir\u00e1n dirigidas a los deportistas nacidos y nacidas en los a\u00f1os 2010, 2011y 2012.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"color: #000000;\">Cada generaci\u00f3n, por separado, realizar\u00e1 3 sesiones de entrenamientos siendo las convocatorias cerradas desde el principio, y concluiremos con una jornada denominada Torneo de Gipuzkoa entre las 4 comarcas (Donostialdea-Oiarso-Bidasoa, Urola Kosta, Goierri-Tolosaldea, Deba Garaia &#8211; Deba Behea)<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"color: #000000;\">Cada comarca tiene designado un coordinador que en pr\u00f3ximas fechas contactar\u00e1 con los clubes de su zona para concretar lugares de entrenamiento, horarios y convocatorias.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"color: #000000;\"><strong>Donostialdea-Oiarso-Bidasoa:<\/strong> Be\u00f1at Mugika<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"color: #000000;\"><strong>Urola kosta:<\/strong> Dan Lertxundi<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"color: #000000;\"><strong>Deba Garaia &#8211; Deba Behea:<\/strong> I\u00f1aki Ogara<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"color: #000000;\"><strong>Goierri &#8211; Tolosaldea:<\/strong> Oskar Rodriguez<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"color: #000000;\">En breves fechas informaremos de los d\u00edas en que se realizar\u00e1n las actividades de tecnificaci\u00f3n con cada generaci\u00f3n durante los meses de marzo, abril y mayo.<\/span><\/p>\n<p style=\"font-weight: 400;\">\u00a0<\/p>\n<p style=\"font-weight: 400;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como todas las temporadas vamos adelantando la informaci\u00f3n correspondiente a las tecnificaciones organizadas por esta Federaci\u00f3n y que dar\u00e1n el pistoletazo de salida en&#8230;<\/p>\n","protected":false},"author":2,"featured_media":5321,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[6],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/5320"}],"collection":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/comments?post=5320"}],"version-history":[{"count":0,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/5320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media\/5321"}],"wp:attachment":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media?parent=5320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/categories?post=5320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/tags?post=5320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}