{"id":5315,"date":"2023-02-14T12:48:38","date_gmt":"2023-02-14T11:48:38","guid":{"rendered":"https:\/\/www.gisaski.eus\/?p=5315\/"},"modified":"2023-03-15T18:37:09","modified_gmt":"2023-03-15T17:37:09","slug":"cj7-23","status":"publish","type":"post","link":"https:\/\/www.gisaski.eus\/es\/cj7-23\/","title":{"rendered":"Cr\u00f3nica de la jornada."},"content":{"rendered":"<p><span style=\"color: #000000;\">Comenzamos el repaso a la jornada de este fin de semana destacando lo ocurrido en nuestro partido de la jornada. Los cadetes Betieder Andraitz firmaron un gran partido para ganar al Efik ISB (65-51) y abrir brecha en la clasificaci\u00f3n de rendimiento masculino A-1, distancia que ya tienen las chicas del ZAST Kuraye que siguen a ritmo de triunfo (5-0 de balance).<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00a0En la categor\u00eda Junior, EASO Basket Plagamania dio un \u201cpu\u00f1etazo\u201d encima de la mesa venciendo a domicilio al segundo clasificado, Goierri UZ Baleike, demostrando que son el equipo a batir en rendimiento femenino A-1, mientras que A-2, Alo\u00f1a Mendi logr\u00f3 superar en un bonito partido al Atl\u00e9tico SN SN Garazi, 51-47, igual\u00e1ndole en el liderato de\u00a0 la clasificaci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">En senior cabe resaltar la gran emoci\u00f3n que reina en la Primera Femenina con tres equipos que no ceden y que volvieron a ganar este fin de semana para mantener la igualdad reinante en la clasificaci\u00f3n, adem\u00e1s de la gran victoria del Ama Guadalupekoa Ikasbasket, de segunda masculina A-2, por 80-62 sobre el l\u00edder, Goierri Modelos Ezguba, que les deja con tan solo un partido de distancia en la clasificaci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">Terminamos con infantiles donde acabamos de arrancar con la segunda fase de las competiciones de rendimiento.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comenzamos el repaso a la jornada de este fin de semana destacando lo ocurrido en nuestro partido de la jornada. Los cadetes Betieder Andraitz&#8230;<\/p>\n","protected":false},"author":2,"featured_media":5316,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[238,73],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/5315"}],"collection":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/comments?post=5315"}],"version-history":[{"count":0,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/5315\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media\/5316"}],"wp:attachment":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media?parent=5315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/categories?post=5315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/tags?post=5315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}