{"id":4617,"date":"2021-12-07T11:09:07","date_gmt":"2021-12-07T10:09:07","guid":{"rendered":"https:\/\/www.gisaski.eus\/?p=4617\/"},"modified":"2023-03-15T18:40:20","modified_gmt":"2023-03-15T17:40:20","slug":"formacion-continua","status":"publish","type":"post","link":"https:\/\/www.gisaski.eus\/es\/formacion-continua\/","title":{"rendered":"Formaci\u00f3n continua a los \u00e1rbitros de la Escuela."},"content":{"rendered":"<p><span style=\"color: #000000;\">Durante los \u00faltimos meses se est\u00e1 llevando a cabo una formaci\u00f3n continua y variada de los \u00e1rbitros de la escuela.<\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"color: #ff6600;\"><strong><em>\u00bfEscuela de \u00e1rbitros?<\/em><\/strong><\/span> Si, la escuela de \u00e1rbitros es una herramienta de formaci\u00f3n continua, alimentando el arbitraje desde la base y pudiendo dar calidad al servicio a la competici\u00f3n. Est\u00e1 abierta a todos los \u00e1rbitros que est\u00e1n empezando y quieren tener un seguimiento y formaci\u00f3n personalizada. El objetivo es que tengan unas pautas para trabajar, se sientan arropados y establecer un m\u00e9todo de trabajo para poderlos ir promocionando a categor\u00edas superiores.<\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"color: #ff6600;\"><strong><em>\u00bfEn qu\u00e9 consiste?<\/em><\/strong><\/span> Este \u00faltimo mes se ha llegado un acuerdo con el IDK Gipukoa, uno de nuestros equipos de referencia y que disputa la LF, para arbitrar sus entrenamientos. All\u00ed acuden 4 \u00e1rbitros de la escuela que van rotando entre s\u00ed con un t\u00e9cnico que va haciendo un informe de su arbitraje. Adem\u00e1s el entrenamiento es grabado para despu\u00e9s poder verlo juntos en clase y analizar las cosas bien hechas y las que se pueden mejorar. Adem\u00e1s, a estas clases se suman, tambi\u00e9n, anotadores en pr\u00e1cticas de 24 segundos y acta digital para que los \u00e1rbitros de la escuela se acostumbren a estas situaciones.<\/span><\/p>\n<p><span style=\"color: #000000;\">Cada jueves, adem\u00e1s, hay una serie de clases que se dividen en 3 tipos:<\/span><\/p>\n<p><span style=\"color: #000000;\">&#8211;<strong>Repaso de videos<\/strong> de los entrenamientos anteriormente comentados o partidos con informe.<\/span><\/p>\n<p><span style=\"color: #000000;\">&#8211;<strong>Test de reglas<\/strong> con correcci\u00f3n en grupo y \u00e9nfasis en un punto del reglamento.<\/span><\/p>\n<p><span style=\"color: #000000;\">&#8211;<strong>Clase de pista entre \u00e1rbitros de la escuela y \u00e1rbitros de provincial<\/strong>.\u00a0 Viene a ser como arbitrar un entrenamiento pero pudiendo parar mucho m\u00e1s, trabajando tambi\u00e9n se\u00f1alizaci\u00f3n y jugadas espec\u00edficas y cohesionando el grupo de la escuela con el grupo de \u00e1rbitros m\u00e1s veteranos que asisten a las clases.<\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"color: #ff6600;\"><strong><em>\u00bfQui\u00e9nes participan? <\/em><\/strong><\/span>Como hemos indicado anteriormente, la escuela est\u00e1 abierta a todos aquellos \u00e1rbitros que est\u00e1n arrancando. Actualmente est\u00e1n doce \u00e1rbitros:<\/span><\/p>\n<p><em><span style=\"color: #000000;\">Maitane Barradas, Oscar Pav\u00f3n, Isaac Kemessi, Jon Zabalza, Iker Telleria, Iv\u00e1n V\u00e1zquez, Cristopher Blacio, Raul Morlans, Guillermo Mart\u00ednez, Koldo S\u00e1nchez, Mikel Mateos, y Javi Koka.<\/span><\/em><\/p>\n<p><span style=\"color: #000000;\">Otra de las principales l\u00edneas de trabajo es la de los<strong> informes en pista<\/strong>. Se han sentado unas bases de designaciones para intentar que los \u00e1rbitros de la escuela vayan acompa\u00f1ados al mayor n\u00famero de partidos posible. En estos partidos acompa\u00f1ados, desde la federaci\u00f3n, se les designa un \u00e1rbitro principal (dentro de un grupo de \u00e1rbitros seleccionados) que debe elaborar un informe por medio de un formulario, ya generado, sobre el \u00e1rbitro tutelado. Esto permite tener una foto de donde est\u00e1n individualmente y que se debe trabajar para alcanzar los objetivos marcados.<\/span><\/p>\n<p><span style=\"color: #000000;\">As\u00ed mismo, se considera que la opini\u00f3n de los tutorizados es muy importante por lo que se han creado dos formularios de control an\u00f3nimos para las clases y los partidos tutorizados. Esto permite obtener un \u201cfeedback\u201d de control sobre la calidad del trabajo realizado.<\/span><\/p>\n<p><span style=\"color: #000000;\">De cara al futuro pr\u00f3ximo, se est\u00e1 trabajando, tambi\u00e9n, en un nuevo sistema de validar los cursos, crear puentes PDJ \u00e1rbitro federado etc.<\/span><\/p>\n<p><span style=\"color: #000000;\">El estamento arbitral es un servicio a la competici\u00f3n y como tal tiene que mantenerse actualizado, irse renovando y estar al d\u00eda con la competici\u00f3n. No paramos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante los \u00faltimos meses se est\u00e1 llevando a cabo una formaci\u00f3n continua y variada de los \u00e1rbitros de la escuela. \u00bfEscuela de \u00e1rbitros? Si,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4618,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[231,72],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/4617"}],"collection":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/comments?post=4617"}],"version-history":[{"count":0,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/4617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media\/4618"}],"wp:attachment":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media?parent=4617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/categories?post=4617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/tags?post=4617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}