{"id":4614,"date":"2021-12-01T12:21:06","date_gmt":"2021-12-01T11:21:06","guid":{"rendered":"https:\/\/www.gisaski.eus\/?p=4614\/"},"modified":"2022-01-07T09:27:24","modified_gmt":"2022-01-07T08:27:24","slug":"cj14-c","status":"publish","type":"post","link":"https:\/\/www.gisaski.eus\/es\/cj14-c\/","title":{"rendered":"Cr\u00f3nica de la jornada."},"content":{"rendered":"<p><span style=\"color: #000000;\">Jornada importante la que hemos tenido este pasado fin de semana, antes del par\u00f3n que vivir\u00e1n nuestras competiciones a causa del puente de la constituci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">A destacar para empezar, en senior, la gran victoria del Bergara Soraluce, de Primera masculina, que protagoniz\u00f3 la gran sorpresa de la jornada al derrotar por 48-46 al col\u00edder Atl\u00e9tico SN SN que llegaba en un gran momento de forma, y el triunfo del Arri BKL Biruin sobre SaskiAxular (61-60), Segunda Masculina, que les deja empatados en la cabeza de la clasificaci\u00f3n. En las categor\u00edas femeninas, subrayar al Inter de Intxaurrondo que se mantiene como gran perseguidor del EASO, en primera femenina antes de encontrarse en la cancha en la pr\u00f3xima jornada.<\/span><\/p>\n<p><span style=\"color: #000000;\">En Junior la noticia fue la derrota del Goierri Gaestopas (77-65) en Beasain en rendimiento masculino y que vuelve a abrir el abanico de candidatos con cuatro equipos en una victoria de diferencia y en categor\u00eda cadete rendimiento, tambi\u00e9n en chicos, ZAST Zarautz asalt\u00f3 Azkoitia (57-70) y se queda como l\u00edder en solitario de la categor\u00eda.<\/span><\/p>\n<p><span style=\"color: #000000;\">Por \u00faltimo, sin dejar el Iraurgi Marmoles Aztiria ISB contin\u00faa con paso firme (8-0) dominando la categor\u00eda infantil femenina de rendimiento, mientras que el EASO Cromova, l\u00edder masculino, descans\u00f3.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ahora descanso de unos d\u00edas para cargar pilas y volver con m\u00e1s fuerzas de cara a las jornadas pre-navide\u00f1as.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jornada importante la que hemos tenido este pasado fin de semana, antes del par\u00f3n que vivir\u00e1n nuestras competiciones a causa del puente de la&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4615,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[238,72,73],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/4614"}],"collection":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/comments?post=4614"}],"version-history":[{"count":0,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/4614\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media\/4615"}],"wp:attachment":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media?parent=4614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/categories?post=4614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/tags?post=4614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}