{"id":219,"date":"2017-09-27T09:51:40","date_gmt":"2017-09-27T07:51:40","guid":{"rendered":"http:\/\/www.gisaski.eus\/?p=219"},"modified":"2017-10-25T11:46:43","modified_gmt":"2017-10-25T09:46:43","slug":"las-selecciones-continuan-preparando-los-campeonatos-euskadi","status":"publish","type":"post","link":"https:\/\/www.gisaski.eus\/es\/las-selecciones-continuan-preparando-los-campeonatos-euskadi\/","title":{"rendered":"Las selecciones contin\u00faan preparando los Campeonatos de Euskadi"},"content":{"rendered":"<p dir=\"ltr\">Este domingo nuestras selecciones infantiles y cadetes realizar\u00e1n la tercera sesi\u00f3n de entrenamiento de cara al Campeonato de Euskadi que se celebrar\u00e1 a finales de octubre.<\/p>\n<p dir=\"ltr\"><img loading=\"lazy\" class=\"wp-image-220 aligncenter\" src=\"http:\/\/www.gisaski.eus\/site\/contenido\/media\/seleccion-cad-fem.jpg\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/www.gisaski.eus\/site\/contenido\/media\/seleccion-cad-fem.jpg 1200w, https:\/\/www.gisaski.eus\/site\/contenido\/media\/seleccion-cad-fem-768x576.jpg 768w, https:\/\/www.gisaski.eus\/site\/contenido\/media\/seleccion-cad-fem-470x353.jpg 470w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p dir=\"ltr\">Poco a poco los seleccionadores van definiendo sus plantillas. El domingo volver\u00e1n a reunirse en el colegio La Salle Donostia para continuar trabajando.<\/p>\n<p dir=\"ltr\" style=\"text-align: center;\"><strong>Convocatoria Cadete Masculina |1 de octubre. 17:30 Colegio La Salle Donostia<\/strong><\/p>\n<p dir=\"ltr\">EASO: Aitor Anabitarte, Guillermo Gonz\u00e1lez, Imanol Sarasola, I\u00f1aki Bernabeu, Mikel Bango, Xabier Bastida.<\/p>\n<p dir=\"ltr\">GOIERRI: Oier Chico.<\/p>\n<p dir=\"ltr\">IRAURGI: Joseba Azpillaga, Manex Ansorregi.<\/p>\n<p dir=\"ltr\">OINTXE: Aitzol Lagunilla.<\/p>\n<p dir=\"ltr\">TAKE : Euken Huici.<\/p>\n<p dir=\"ltr\">ZAST : Imanol Artetxe.<\/p>\n<p dir=\"ltr\">Seleccionador: Alberto Aus\u00edn<\/p>\n<p dir=\"ltr\" style=\"text-align: center;\"><strong>Convocatoria Cadete Femenina | 1 de octubre, 17:30 Colegio La Salle Donostia<\/strong><\/p>\n<p dir=\"ltr\">EASO: Ainhoa Aizpitarte, Jimena Cobo, Uxue Etxarte, Irati Fajarnes, Judith Navarro, Patricia Oregui, Nora Yurrita.<\/p>\n<p dir=\"ltr\">HONDARRIBIA: Nagore Vallejo.<\/p>\n<p dir=\"ltr\">IRAURGI: Maria Otaegi, Paula San Juan.<\/p>\n<p dir=\"ltr\">OINTXE: Haizea Apellaniz, Nahia Badiola, Saioa Carrascal, Irene Murua, Teresa Isabel Mbomio.<\/p>\n<p dir=\"ltr\">Seleccionador: Luis Agirre<\/p>\n<p dir=\"ltr\" style=\"text-align: center;\"><strong>Convocatoria Infantil Masculina |1 de octubre, 16:00 Colegio La Salle Donostia<\/strong><\/p>\n<p dir=\"ltr\">ASKATUAK: Ivan Fraile.<\/p>\n<p dir=\"ltr\">BKL: Urko P\u00e9rez.<\/p>\n<p dir=\"ltr\">EASO: I\u00f1igo Anduaga, Julen Zulaika, Iker Simon, E\u00f1aut Bauza.<\/p>\n<p dir=\"ltr\">IRAURGI: Igor Olazabal, Lander Mu\u00f1oz, Mikel Iriondo.<\/p>\n<p dir=\"ltr\">OINTXE: Gorka Vicente.<\/p>\n<p dir=\"ltr\">ORDIZIA: Xuban de Prado, Julen Zufiria.<\/p>\n<p dir=\"ltr\">TAKE: Be\u00f1at Etxeberria.<\/p>\n<p dir=\"ltr\">ZAST: Nikola Rekalde.<\/p>\n<p dir=\"ltr\">Seleccionador: I\u00f1igo Martiarena<\/p>\n<p dir=\"ltr\" style=\"text-align: center;\"><strong>Convocatoria Infantil Femenina | 1 de octubre 16:00 Colegio La Salle Donostia<\/strong><\/p>\n<p dir=\"ltr\">EASO: Nora Ramos, Aitana Aldaz, Beatriz Artamendi.<\/p>\n<p dir=\"ltr\">HONDARRIBIA: Emma Vallejo, Naiara Sand\u00edn.<\/p>\n<p dir=\"ltr\">IRAURGI: Ainhoa Aranbarri, June Ansorregi, Naiara Muguruza, Arantxa Sudupe.<\/p>\n<p dir=\"ltr\">ORDIZIA: Elene Sarasola, Arene Etxeberria, Paula Elzaurdi.<\/p>\n<p dir=\"ltr\">ZAST: Nora Bereziartua, Iraia Alday.<\/p>\n<p dir=\"ltr\">Seleccionador: Asier Recondo<\/p>\n<p dir=\"ltr\">*Los convocados\/as deber\u00e1n presentarse 15 minutos antes de la hora programada y con camiseta blanca y de color.<\/p>\n<p dir=\"ltr\">Mucha suerte a todos los convocados para estos entrenamientos del domingo.<\/p>\n<p dir=\"ltr\" style=\"text-align: right;\"><strong>FGB<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este domingo nuestras selecciones infantiles y cadetes realizar\u00e1n la tercera sesi\u00f3n de entrenamiento de cara al Campeonato de Euskadi que se celebrar\u00e1 a finales&#8230;<\/p>\n","protected":false},"author":2,"featured_media":220,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[7],"tags":[39,67,20],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/219"}],"collection":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/comments?post=219"}],"version-history":[{"count":0,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/posts\/219\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media\/220"}],"wp:attachment":[{"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/media?parent=219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/categories?post=219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gisaski.eus\/es\/wp-json\/wp\/v2\/tags?post=219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}